 {"id":6090,"date":"2022-08-26T16:49:00","date_gmt":"2022-08-26T09:49:00","guid":{"rendered":"https:\/\/extremenomads.life\/?p=6090"},"modified":"2023-05-11T16:32:02","modified_gmt":"2023-05-11T11:32:02","slug":"khao-sam-roi-yot-national-park","status":"publish","type":"post","link":"https:\/\/extremenomads.life\/de\/khao-sam-roi-yot-national-park\/","title":{"rendered":"Khao Sam Roi Yot National Park: 7 coolste Outdoor-Abenteuer"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Erkundung des Khao Sam Roi Yot Nationalparks: Unser Abenteuer in der Wildnis<\/h2>\n\n\n\n<p>Khao Sam Roi Yot National Park (manchmal auch Sam Roi Yod genannt, was wir w\u00f6rtlich \u00fcbersetzen k\u00f6nnen mit <em>Berg der 300 Gipfel<\/em>) ist ein traumhaftes St\u00fcck Paradies auf der westlichen Seite des Golfs von Thailand.<\/p>\n\n\n\n<p>Khao Sam Roi Yot ist Thailands erster Meeresnationalpark mit S\u00fcmpfen, Mangroven, Bergen, Ackerland, Str\u00e4nden, Inseln und kleinen authentischen D\u00f6rfern. <a href=\"https:\/\/extremenomads.life\/de\/adventure-in-thailand-things-to-do\/\">Abenteuer<\/a>, Adrenalin und ein Blick auf das allt\u00e4gliche Leben in der sch\u00f6nen thail\u00e4ndischen Landschaft.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Nach fast einem Jahr Aufenthalt in Thailand ist einer meiner Lieblingsorte im ganzen Land immer noch unser Hinterhof.<\/p>\n\n\n\n<p>Hinter unserem winzigen Haus befindet sich ein gro\u00dfer, felsiger, mit Gestr\u00fcpp bewachsener H\u00fcgel, auf dem unsere adoptierte \"Soi-H\u00fcndin\" (sprich: Stra\u00dfenhund) gerne mit ihren anderen struppigen Soi-Hunde-Freunden herumtollt.<\/p>\n\n\n\n<div class=\"wp-block-ta-image wp-block-image size-full wp-image-7259\"><figure class=\"aligncenter\"><ta><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/extremenomads.life\/wp-content\/uploads\/2018\/12\/phraya-nakhon-start.jpg\" alt=\"Phraya Nakhon H\u00f6hle Sam Roi Yot National Park\" class=\"wp-image-7259\" srcset=\"https:\/\/extremenomads.life\/wp-content\/uploads\/2018\/12\/phraya-nakhon-start.jpg 800w, https:\/\/extremenomads.life\/wp-content\/uploads\/2018\/12\/phraya-nakhon-start-768x432.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/ta><figcaption><\/figcaption><\/figure><\/div>\n\n\n\n<p>Von oben haben wir einen 360-Grad-Blick auf die umliegende Landschaft, der so verdammt sch\u00f6n ist, dass es kriminell ist, dass wir immer noch f\u00fcr ein Netflix-Abo bezahlen (Laster, Mann...).<\/p>\n\n\n\n<p>Im Osten gibt es ein paar sanfte H\u00fcgel mit dichtem Bambuswald, wilden Pfauen und einem kleinen buddhistischen Tempel.<\/p>\n\n\n\n<p>Im Westen haben wir einen weiten Blick auf die Landschaft von Pranburi; die H\u00e4user, D\u00f6rfer, Ananasfelder und Palmen erstrecken sich kilometerweit, bis sie die \u00e4u\u00dfersten Berge am Fu\u00dfe des Pranburi-Damms erreichen.<\/p>\n\n\n\n<p>Zwischen jedem dieser Ausblicke haben wir einen freien Blick auf unsere Hauptattraktion, den Khao Sam Roi Yot National Park.<\/p>\n\n\n\n<p>Obwohl wir buchst\u00e4blich dutzende Male mit dem Motorrad durch den Khao Sam Roi Yot National Park gefahren sind, haben wir nur <em>gestern<\/em> Wir haben es geschafft, etwas zu tun, was wir schon seit Ewigkeiten tun wollten:<\/p>\n\n\n\n<p>Radeln Sie von unserem Haus in <a href=\"https:\/\/extremenomads.life\/de\/pranburi-thailand-travel-guide\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pranburi<\/a> zum Nationalpark.<\/p>\n\n\n\n<p>Und zur\u00fcck.<\/p>\n\n\n\n<p>Unn\u00f6tig zu sagen, dass meine Beine heute so steif sind wie das Schloss am Keuschheitsg\u00fcrtel einer Nonne - aber das gibt mir einen noch besseren Grund, mich hinzusetzen und diesen Artikel \u00fcber Sam Roi Yot und seine <em>wahnsinnig<\/em> Outdoor-Abenteuer-Potenzial.<\/p>\n\n\n\n<p>Also los geht's, Chappies:<\/p>\n\n\n\n<p>Dies ist Ihr vollgepackter Reisef\u00fchrer zum Khao Sam Roi Yot National Park. Ich verrate Ihnen die besten Outdoor-Aktivit\u00e4ten, die Sie dort unternehmen k\u00f6nnen, sowie viele weitere wertvolle Informationen \u00fcber das Wetter, die Highlights, die Anreise und wie Sie den Park am besten in Ihre Thailand-Reise einbauen.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">7 l\u00e4cherlich gro\u00dfartige Outdoor-Abenteuer im Khao Sam Roi Yot National Park<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Wanderung zur Phraya Nakhon H\u00f6hle<\/h3>\n\n\n\n<p>Wenn es eine Sache gibt, die Sie vielleicht schon \u00fcber den Sam Roi Yot National Park wissen, dann ist es wahrscheinlich <a href=\"https:\/\/extremenomads.life\/de\/phraya-nakhon-cave-thailand\/\">Phraya Nakhon H\u00f6hle<\/a>.<\/p>\n\n\n\n<p>Die H\u00f6hle ist \u00fcber den Laem Son Beach zu erreichen und erfordert eine etwa einst\u00fcndige Wanderung den steilen Berghang hinauf, bis Sie die beiden klaffenden H\u00f6hlen erreichen, in denen sich der magisch anmutende Pavillon befindet, der zu Ehren von K\u00f6nig Rama V. errichtet wurde.<\/p>\n\n\n\n<p>Die Phraya-Nakhon-H\u00f6hle und ihr innerer Pavillon, ein Wahrzeichen der Provinz Prachuap Khiri Khan, sind am besten zu sehen, wenn das morgendliche Sonnenlicht durch das eingest\u00fcrzte Dach f\u00e4llt und die innere H\u00f6hle beleuchtet.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-ta-image wp-block-image size-full wp-image-7258\"><figure class=\"aligncenter\"><ta><img loading=\"lazy\" decoding=\"async\" width=\"1400\" height=\"843\" src=\"https:\/\/extremenomads.life\/wp-content\/uploads\/2018\/12\/phraya-nakhon-gopro.jpg\" alt=\"K\u00f6niglicher Pavillon in der Phraya Nakhon H\u00f6hle\" class=\"wp-image-7258\" srcset=\"https:\/\/extremenomads.life\/wp-content\/uploads\/2018\/12\/phraya-nakhon-gopro.jpg 1400w, https:\/\/extremenomads.life\/wp-content\/uploads\/2018\/12\/phraya-nakhon-gopro-768x462.jpg 768w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/><\/ta><figcaption>Der k\u00f6nigliche Pavillon in der Phraya Nakhon H\u00f6hle.<\/figcaption><\/figure><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Beginnen Sie Ihre Wanderung um 8 Uhr und erreichen Sie die H\u00f6hle um 9.30 Uhr. Halten Sie auf dem R\u00fcckweg am Strand an und springen Sie ins Wasser, um den Schwei\u00df und den Schmutz der H\u00f6hle abzuwaschen!<\/p>\n\n\n\n<p>Die Phraya-Nakhon-H\u00f6hle hat sich in der viralen Internetwelt einen Namen gemacht. Bilder und Videos des Pavillons haben Millionen von Ansichten angeh\u00e4uft und die Aufmerksamkeit abenteuerlustiger Reisender in Thailand geweckt.<\/p>\n\n\n\n<p>Doch selbst mit ihrem neu gewonnenen Internet-Ruhm bedeutet die abgelegene Lage der H\u00f6hle (und der kleine Tourismus in der Gegend), dass Phraya Nakhon immer noch friedlich und (meistens) frei von Menschenmassen ist.<\/p>\n\n\n\n<p>Gehen Sie jetzt, bevor sich alles \u00e4ndert.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Paddle Boarding am Sam Roi Yot Strand<\/h3>\n\n\n\n<p>Wenn Sie so sind wie wir, werden Sie zustimmen, dass SUPing (oder Stand-up-Paddle-Boarding) eine der besten M\u00f6glichkeiten ist, Wasserzeit, Fitness und Sightseeing in einem zu kombinieren. Wann immer wir an einen neuen Ort an der K\u00fcste oder an einem Fluss reisen, lieben wir es, ein paar Paddle Boards zu mieten und loszuziehen, um sie zu erkunden.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-ta-image wp-block-image wp-image-6475 size-full\"><figure class=\"aligncenter\"><ta><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"460\" src=\"https:\/\/extremenomads.life\/wp-content\/uploads\/2018\/09\/samroiyot-sup-2.jpg\" alt=\"Paddelboarding am Strand von Sam Roi Yot\" class=\"wp-image-6475\" srcset=\"https:\/\/extremenomads.life\/wp-content\/uploads\/2018\/09\/samroiyot-sup-2.jpg 800w, https:\/\/extremenomads.life\/wp-content\/uploads\/2018\/09\/samroiyot-sup-2-768x442.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/ta><figcaption>Perfektes Setup, um unser neues aufblasbares SUP von Starboard zu testen!<\/figcaption><\/figure><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Der Sam Roi Yot Beach, der auf die Dolphin Bay hinausgeht, ist ein idealer Ort zum Paddelboarding. Die gesch\u00fctzte Bucht bekommt nur selten Wellen ab, das Wasser ist kristallklar und es gibt ein paar vorgelagerte Inseln in Paddeldistanz.<\/p>\n\n\n\n<p>Zur\u00fcck auf der Strandseite gibt es goldenen Sand und Palmen - viele Palmen.<\/p>\n\n\n\n<p>Abgesehen von ein paar Fischerbooten und dem einen oder anderen Touristen hier und da, ist der Strand normalerweise leer. Wie oft h\u00f6rt man das \u00fcber thail\u00e4ndische Str\u00e4nde?! Wenn es eine Sache gibt, die der Sam Roi Yot Strand deutlich macht, dann ist es, dass es sich wirklich lohnt, die ausgetretenen Touristenpfade zu verlassen.<\/p>\n\n\n\n<p>Es gibt ein paar lokale Unternehmen entlang der Strandstra\u00dfe, die Paddelbretter f\u00fcr etwa 300 Baht\/Stunde (weniger als $10 USD) vermieten. Halten Sie einfach Ausschau nach den Schildern oder - noch offensichtlicher - nach den Brettern, die am Stra\u00dfenrand aufgestapelt sind.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Mit dem Kajak zur Affeninsel<\/h3>\n\n\n\n<p>Erinnern Sie sich an die Inseln, die wir oben erw\u00e4hnt haben? Eine davon ist Monkey Island, die - wie Sie sich denken k\u00f6nnen - einer der besten Orte im Khao Sam Roi Yot Nationalpark ist, um unsere frechen, pelzigen, kackenden Freunde zu beobachten (nur ein Scherz, ich habe tats\u00e4chlich keine Ahnung, ob diese Affen die kackende Art sind).<\/p>\n\n\n\n<p>Normalerweise entscheiden sich die meisten Touristen daf\u00fcr, mit einem der lokalen Fischerboote zur Insel zu fahren, aber wir meinen, eine noch coolere Art, Monkey Island zu erreichen, ist mit Ihrem eigenen Kajak.<\/p>\n\n\n\n<p>Kajaks k\u00f6nnen bei vielen lokalen Gesch\u00e4ften entlang der Stra\u00dfe am Sam Roi Yot Beach gemietet werden und kosten normalerweise etwa 200-300 Baht\/Stunde (mit Rabatten f\u00fcr Halb- und Ganztagesmieten).<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Gleitschirmfliegen \u00fcber dem Khao Sam Roi Yot National Park<\/h3>\n\n\n\n<p>Wenn Sie schon dachten, dass dieser Ort vom Boden aus sch\u00f6n ist, dann warten Sie nur, bis Sie ihn von oben gesehen haben. Und das k\u00f6nnen Sie auch, denn der Khao Sam Roi Yot National Park ist die Heimat des etabliertesten Clans von Gleitschirmfliegern auf dieser Seite des Golfs: 300 Peaks Paragliding.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div align=\"middle\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/BgF-P0FnTeR\/?utm_source=ig_embed&amp;utm_medium=loading\" data-instgrm-version=\"12\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\"><div style=\"padding: 16px;\">\n<p><a href=\"https:\/\/www.instagram.com\/p\/BgF-P0FnTeR\/?utm_source=ig_embed&amp;utm_medium=loading\" style=\"background: #FFFFFF; line-height: 0; padding: 0 0; text-align: center; text-decoration: none; width: 100%;\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"> <\/a><\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><svg width=\"50px\" height=\"50px\" viewbox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<p><\/p>\n<p style=\"margin: 8px 0 0 0; padding: 0 4px;\"><a href=\"https:\/\/www.instagram.com\/p\/BgF-P0FnTeR\/?utm_source=ig_embed&amp;utm_medium=loading\" style=\"color: #000; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none; word-wrap: break-word;\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">#flyinghome #byethailand #khaokalok #farewell #backsoon #300peaksparagliding #cloudsurfing<\/a><\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\">Une publication partag\u00e9e par @<a href=\"https:\/\/www.instagram.com\/yo_bill\/?utm_source=ig_embed&amp;utm_medium=loading\" style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px;\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"> yo_bill<\/a> le <time style=\"font-family: Arial,sans-serif; font-size: 14px; line-height: 17px;\" datetime=\"2018-03-09T07:00:59+00:00\">8 Mars 2018 \u00e0 11 :00 PST<\/time><\/p>\n<\/div><\/blockquote>\n<p><script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Benannt nach dem Nationalpark selbst, bietet die 300 Peaks Crew aufregende Tandemfl\u00fcge und Pilotentrainingskurse in und um das Gebiet von Khao Sam Roi Yot an. Typischerweise beginnen ihre Fl\u00fcge mit einem Tow-up am Strand und f\u00fchren Sie \u00fcber die Berge, Ebenen und Str\u00e4nde.<\/p>\n\n\n\n<p><em>UPDATE (August 2019): 300 Peaks Thailand sind derzeit nicht in Betrieb, da sich die Piloten auf andere Projekte konzentrieren. Leider ist diese Aktivit\u00e4t derzeit nicht in Sam Roi Yot verf\u00fcgbar! Kontaktieren Sie das 300 Peaks Team \u00fcber Facebook oder auf ihrer Website f\u00fcr weitere Informationen.<\/em><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Radfahren durch die Ausl\u00e4ufer des Khao Sam Roi Yot Nationalparks<\/h3>\n\n\n\n<p>Dies ist das Outdoor-Abenteuer, von dem wir Ihnen am liebsten erz\u00e4hlen w\u00fcrden, denn es ist dasjenige, von dem wir <em>nur<\/em> gestern geknackt.<\/p>\n\n\n\n<p>Der Khao Sam Roi Yot-Nationalpark ist dank seiner wundersch\u00f6nen Landschaft, den friedlichen, von B\u00e4umen ges\u00e4umten Stra\u00dfen und den versteckten Feldwegen durch das Ackerland ein idealer Ort f\u00fcr ein Abenteuer auf zwei R\u00e4dern.<\/p>\n\n\n\n<p>Abgesehen von den mega steilen Bergen ist das Gel\u00e4nde rund um Sam Roi Yot meist flach und weist kaum Erhebungen auf. Das sorgt f\u00fcr eine gro\u00dfartige Kombination aus einfachem Fahren auf der Stra\u00dfe und etwas technischerem Mountainbiken im Gel\u00e4nde.<\/p>\n\n\n\n<p>Wir mieteten ein paar tolle, leichte Mountainbikes vom Bike Point Pak Nam Pran und radelten die 20 km von ihrem Hauptquartier bis zum Ende des Sam Roi Yot Beach und auf dem R\u00fcckweg durch die Ausl\u00e4ufer der Berge.<\/p>\n\n\n\n<p>Sicherlich ist der gesamte Nationalpark mit dem Fahrrad zu erkunden (man kann die Ruhe und Stille so viel mehr genie\u00dfen, als wenn man mit dem Motorrad \u00fcber die Stra\u00dfe braust), aber das Highlight f\u00fcr uns war die Erkundung der kleinen Landstra\u00dfen an den Ausl\u00e4ufern der Berge. Erwarten Sie authentische thail\u00e4ndische H\u00e4user, viele freundliche Gesichter und Kokosnussb\u00e4ume f\u00fcr Tage.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Camping am Laem Sala Strand<\/h3>\n\n\n\n<p>Das ist also eines der Outdoor-Abenteuer in Sam Roi Yot, das wir noch von unserer eigenen Liste abhaken m\u00fcssen (denn, nun ja, es ist Regenzeit, und das Zelt, das ich gekauft habe, sieht aus, als w\u00fcrde es sich gegen einen Spucknapf wehren, geschweige denn gegen einen tropischen Regenguss. Fairerweise muss man aber sagen, dass es nur 250 Baht gekostet hat).<\/p>\n\n\n\n<p>Trotzdem steht das Campen in Laem Sala ganz oben auf unserer To-Do-Liste, sobald der Wettergott mit uns kooperiert! Und das sollte es auch bei Ihnen sein.<\/p>\n\n\n\n<p>Der Laem Sala Beach liegt am Fu\u00dfe des Berges, in dem sich die Phraya Nakhon H\u00f6hle befindet. Er ist abgelegen, ruhig, nicht \u00fcberlaufen und verdammt sch\u00f6n - wenn wir das selbst sagen. Der Grund, warum der Laem Sala Beach immer noch frei von Menschenmassen ist, liegt wahrscheinlich darin, dass die einzige M\u00f6glichkeit, den Strand an Land zu erreichen, darin besteht, eine halbst\u00fcndige Wanderung \u00fcber den Berg zu unternehmen.<\/p>\n\n\n\n<p>Keine gro\u00dfe Sache!<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div align=\"middle\">\n<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/Bk6IEOilWpN\/?utm_source=ig_embed&amp;utm_medium=loading\" data-instgrm-version=\"12\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\"><div style=\"padding: 16px;\">\n<p><a href=\"https:\/\/www.instagram.com\/p\/Bk6IEOilWpN\/?utm_source=ig_embed&amp;utm_medium=loading\" style=\"background: #FFFFFF; line-height: 0; padding: 0 0; text-align: center; text-decoration: none; width: 100%;\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"> <\/a><\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><svg width=\"50px\" height=\"50px\" viewbox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p><\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/Bk6IEOilWpN\/?utm_source=ig_embed&amp;utm_medium=loading\" style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Une publication partag\u00e9e par Secret Adventure (@shopsecretadventure)<\/a> le <time style=\"font-family: Arial,sans-serif; font-size: 14px; line-height: 17px;\" datetime=\"2018-07-06T23:12:52+00:00\">6 Juil. 2018 \u00e0 4 :12 PDT<\/time><\/p>\n<\/div><\/blockquote>\n<p><script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Abgesehen von ein paar verstreuten Bungalows und ein oder zwei lokalen Restaurants gibt es am Laem Sala Beach kaum etwas anderes als Pinien und Sand. Zelte kann man vor Ort f\u00fcr 150 Baht\/Nacht mieten.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Verirren am Secret Beach<\/h3>\n\n\n\n<p>Irgendwie schmerzt es uns, dar\u00fcber zu schreiben, denn wir w\u00fcrden es nur zu gerne f\u00fcr uns behalten. Aber wie das Reisen - und das Leben im Allgemeinen - uns lehrt, ist nichts von Dauer, Ver\u00e4nderungen sind unvermeidlich, und der Austausch mit Gleichgesinnten kann viele unerwartete Freuden bringen.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-ta-image wp-block-image wp-image-7291 size-full\"><figure class=\"aligncenter\"><ta><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"594\" src=\"https:\/\/extremenomads.life\/wp-content\/uploads\/2018\/09\/jim-sup-sunrise-sam-roi-yot.jpg\" alt=\"Sonnenaufgang Stand Up Paddle Session in der N\u00e4he von Sam Roi Yot Beach\" class=\"wp-image-7291\" srcset=\"https:\/\/extremenomads.life\/wp-content\/uploads\/2018\/09\/jim-sup-sunrise-sam-roi-yot.jpg 1000w, https:\/\/extremenomads.life\/wp-content\/uploads\/2018\/09\/jim-sup-sunrise-sam-roi-yot-768x456.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/ta><figcaption>Jim pumpt Minuten vor Sonnenaufgang - Secret Beach<\/figcaption><\/figure><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Hier haben Sie ihn also, unseren ganz pers\u00f6nlichen Khao Sam Roi Yot-Favoriten:<\/p>\n\n\n\n<p>Geheimer Strand.<\/p>\n\n\n\n<p>Nun, es ist eigentlich <em>genannt<\/em> Secret Beach, was wohl auf seine eigene Art und Weise ziemlich ironisch ist. Ich meine, der Name steht genau dort zur Ansicht auf Google Maps und so.<\/p>\n\n\n\n<p>Der Secret Beach ist am besten mit dem Roller oder Fahrrad von der Hauptstra\u00dfe in Sam Roi Yot aus zu erreichen. Er ist ein breiter Sandstrand, der entlang der K\u00fcstenlinie zu Ko Rawing und Ko Nom Sao verl\u00e4uft. Der Strand ist mit wundersch\u00f6nen kleinen Muscheln bedeckt - ganz anders als die, die wir an unserem heimischen Strand in Pak Nam Pran finden, so dass wir hier gerne spazieren gehen und von Zeit zu Zeit ein paar besondere Muscheln sammeln.<\/p>\n\n\n\n<p>Es gibt nur ein bewohntes Geb\u00e4ude mit Blick auf den Secret Beach: Brassiere Cozy Beach Resort - und glauben Sie uns, wenn wir sagen, dass diese Strandvilla eine absolute Sch\u00f6nheit ist. Mit ihren wei\u00df get\u00fcnchten W\u00e4nden, luftigen Balkonen und dem \u00fcppigen Garten (mit Pool) ist dies einfach einer der idyllischsten Orte im Khao Sam Roi Yot Nationalpark.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Andere Outdoor-Aktivit\u00e4ten in Khao Sam Roi Yot<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Wildtierbeobachtung<\/h3>\n\n\n\n<p>Am Sam Roi Yot Beach sind Rosa- und Graunasendelfine zu Hause, w\u00e4hrend Sie oben in den Bergen Makaken, Schwarzb\u00fcschel\u00e4ffchen, Schuppentiere und Fischkatzen finden k\u00f6nnen. Auch Vogelbeobachter kommen auf ihre Kosten, denn im Nationalpark sollen mehr als 300 Arten leben.<\/p>\n\n\n\n<p>Aber das ber\u00fchmteste Mitglied des Wildtierclans im Khao Sam Roi Yot Nationalpark ist - ohne Schei\u00df - ein ZIEGENANTELOPE (auch bekannt als Serow).<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-ta-image wp-block-image size-full wp-image-7262\"><figure class=\"aligncenter\"><ta><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"457\" src=\"https:\/\/extremenomads.life\/wp-content\/uploads\/2018\/12\/hike-spider.jpg\" alt=\"goldene Seide Orb Weber thailand\" class=\"wp-image-7262\" srcset=\"https:\/\/extremenomads.life\/wp-content\/uploads\/2018\/12\/hike-spider.jpg 800w, https:\/\/extremenomads.life\/wp-content\/uploads\/2018\/12\/hike-spider-768x439.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/ta><figcaption>Achten Sie auf Ihren Kopf f\u00fcr diese <a href=\"https:\/\/en.wikipedia.org\/wiki\/Golden_silk_orb-weaver\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Golden Silk Orb Weavers<\/a>. Ihr Gift scheint beim Menschen unwirksam zu sein, aber der Biss ist trotzdem etwas.<\/figcaption><\/figure><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Mangrovenwald-Naturlehrpfad<\/h3>\n\n\n\n<p>Wie viele andere Gebiete in Prachuap Khiri Khan beherbergt auch der Khao Sam Roi Yot National Park einen von Menschenhand geschaffenen Mangrovenwald.<\/p>\n\n\n\n<p>Die Mangroven sind reich an exotischer Tierwelt und beherbergen tonnenweise verschiedene Vogelarten (u.a. Eisv\u00f6gel und Purpurreiher) sowie Makaken, Krabben und riesige Warane.<\/p>\n\n\n\n<p>Abgesehen davon, dass sie einen ph\u00e4nomenalen Beitrag zum \u00d6kosystem leisten, bieten die Mangroven auch einen willkommenen Schatten vor der sengenden thail\u00e4ndischen Sonne. Die Erkundung des Mangrovenlehrpfades in Sam Roi Yot ist ebenso lehrreich wie unterhaltsam.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-ta-image wp-block-image\"><ta><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/extremenomads.life\/wp-content\/uploads\/2019\/04\/mangrove-web-12.jpg\" alt=\"Schattige Uferpromenade umgeben von Mangroven im Pranburi Forest Park, Thailand\" class=\"wp-image-8274\" srcset=\"https:\/\/extremenomads.life\/wp-content\/uploads\/2019\/04\/mangrove-web-12.jpg 1200w, https:\/\/extremenomads.life\/wp-content\/uploads\/2019\/04\/mangrove-web-12-768x432.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/ta><figcaption><\/figcaption><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><em>Pssst: wenn Ihnen das gef\u00e4llt, sollten Sie sich unbedingt auch <a href=\"https:\/\/extremenomads.life\/de\/pranburi-forest-park-mangrove\/\">Pranburi Waldpark<\/a> (Bild oben), das nur 30 Minuten entfernt liegt und ein wundersch\u00f6nes Mangrovenreservat, einen Pinienwald und einen Picknickplatz am Strand bietet.<\/em><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Aussichtspunkt Khao Daeng<\/h3>\n\n\n\n<p>Die Wanderung auf den Khao Daeng ist schnell und intensiv; es dauert nur etwa eine halbe Stunde, um den Gipfel zu erreichen, aber es ist steil und das felsige Gel\u00e4nde ist stellenweise uneben - also machen Sie diese Wanderung am besten nur, wenn Sie in guter k\u00f6rperlicher Verfassung sind (f\u00fcr kleine Kinder oder \u00e4ltere Menschen k\u00f6nnte es zu viel sein).<\/p>\n\n\n\n<p>Die Aussicht von oben ist es aber auf jeden Fall wert. Auf knapp 160 Metern H\u00f6he bietet der Aussichtspunkt Khao Daeng eine ziemlich krasse Aussicht auf die umliegende K\u00fcstenlandschaft.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div align=\"middle\">\n<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/BnLYo1qjjaB\/?utm_source=ig_embed&amp;utm_medium=loading\" data-instgrm-version=\"12\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\"><div style=\"padding: 16px;\">\n<p><a href=\"https:\/\/www.instagram.com\/p\/BnLYo1qjjaB\/?utm_source=ig_embed&amp;utm_medium=loading\" style=\"background: #FFFFFF; line-height: 0; padding: 0 0; text-align: center; text-decoration: none; width: 100%;\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"> <\/a><\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><svg width=\"50px\" height=\"50px\" viewbox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Voir cette publication sur Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p><\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/BnLYo1qjjaB\/?utm_source=ig_embed&amp;utm_medium=loading\" style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Une publication partag\u00e9e par Grand Marina Pranburi (@grandmarinapranburi)<\/a> le <time style=\"font-family: Arial,sans-serif; font-size: 14px; line-height: 17px;\" datetime=\"2018-09-01T09:07:33+00:00\">1 Sept. 2018 \u00e0 2 :07 PDT<\/time><\/p>\n<\/div><\/blockquote>\n<p><script async=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Wie einige der anderen Touristenattraktionen im Khao Sam Roi Yot Nationalpark ist auch die Khao Daeng-Wanderung nur zwischen 08.00-15.30 Uhr f\u00fcr Besucher ge\u00f6ffnet, und wenn Sie einen Hund haben, d\u00fcrfen Sie ihn nicht mit auf die Wanderung nehmen (weshalb wir diese auch nicht oft machen!).<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Kaeo und Sai H\u00f6hlen<\/h3>\n\n\n\n<p>Die Kaeo- und Sai-H\u00f6hlen werden oft zugunsten ihrer ber\u00fchmten Nachbarn in Phraya Nakhon \u00fcbersehen, sind aber auch selbst einen Blick wert. Gef\u00fcllt mit Flederm\u00e4usen, Stalaktiten und Stalagmiten, sind beide H\u00f6hlen \u00fcber eine felsige, abgelegene Wanderung zu erreichen.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Sam Phraya Strand<\/h3>\n\n\n\n<p>Der Sam Phraya Beach ist eine nette Alternative zum Laem Son Beach, falls Sie Lust auf ein wenig Abwechslung haben. Der von Pinien ges\u00e4umte Sandstrand dient auch als Campingplatz, auf dem man Zelte f\u00fcr etwas mehr als 200 Baht pro Nacht mieten kann.<\/p>\n\n\n\n<p>Wir wollten vor kurzem den Sam Phraya Beach besuchen, aber als wir am Eingang anhielten, waren wir ziemlich \u00fcberrascht, dass man uns 200 Baht Eintritt f\u00fcr JEDEN von uns abverlangte (das ist der Preis f\u00fcr ausl\u00e4ndische Besucher, und wenn ich mich recht erinnere, sind es 40 Baht f\u00fcr thail\u00e4ndische Besucher).<\/p>\n\n\n\n<p>Wir empfanden das als ziemlich happig, da wir nur einen Strandspaziergang machen wollten - nicht den ganzen Tag dort bleiben. Stattdessen entschieden wir uns, ein wenig weiter die Stra\u00dfe hinunter zu fahren und den Secret Beach zu besuchen, der kostenlos ist.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">S\u00fc\u00dfwasser-Sumpf Thung Sam Roi Yot<\/h3>\n\n\n\n<p>Das sumpfige Feuchtgebiet in der Mitte von Khao Sam Roi Yot war fr\u00fcher eine der beliebtesten Touristenattraktionen, bis vor kurzem die Uferpromenade, die die Besucher um das Sumpfgebiet herumf\u00fchrte, anfing, sich aufzul\u00f6sen.&nbsp;<em>Igitt!<\/em><\/p>\n\n\n\n<p>Gl\u00fccklicherweise wurde die Uferpromenade repariert und ist nun wieder f\u00fcr die \u00d6ffentlichkeit zug\u00e4nglich. Machen Sie sich auf den Weg dorthin, um das Sumpfgebiet zu erkunden, V\u00f6gel zu beobachten und sich in einer familienfreundlichen Umgebung zu entspannen.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">So erreichen Sie den Khao Sam Roi Yot National Park<\/h2>\n\n\n\n<p>Auch wenn ein Besuch in Sam Roi Yot einem das Gef\u00fchl geben kann, dass man sich weit, weit abseits der ausgetretenen Pfade befindet, ist es dank Thailands gro\u00dfartigem \u00f6ffentlichem Verkehrssystem gn\u00e4digerweise leicht zu erreichen.<\/p>\n\n\n\n<p>Abgesehen von der Anmietung eines Privatautos (was etwa $80 USD kostet), gibt es zwei M\u00f6glichkeiten, um nach Sam Roi Yot zu gelangen <a href=\"https:\/\/extremenomads.life\/de\/digital-nomad-bangkok-travel-guide\/\">Bangkok<\/a>: Bus oder Bahn.<\/p>\n\n\n\n<p><em><strong>Lesen Sie mehr: <a href=\"https:\/\/extremenomads.life\/de\/outdoor-activities-bangkok\/\">5 coolste Dinge, die man in Bangkok im Freien tun kann<\/a><\/strong><\/em><\/p>\n\n\n\n<p>Wenn Sie direkt vom Flughafen (BKK) kommen, k\u00f6nnen Sie den direkten VIP-Bus vom Flughafen nach Hua Hin nehmen (oder den lokalen Bus vom Mo Chit Bus Terminal) und von dort ist es am einfachsten, ein Motorrad zu mieten (oder <em>salang<\/em>(das ist wie ein Tuk-Tuk) und erkunden Sie die Gegend selbst. Rechnen Sie damit, etwa 250-300 Baht\/Tag f\u00fcr eine Motorradmiete zu bezahlen.<\/p>\n\n\n\n<p>Wenn Sie keine Lust haben, selbst zu fahren, gibt es viele lokale Tourunternehmen, die Sie f\u00fcr einen Tag in ihrem Auto mitnehmen.<\/p>\n\n\n\n<p>Sie k\u00f6nnen auch den Zug von Bangkok nach Pranburi nehmen und von dort aus Ihr eigenes Motorrad mieten oder mit einem lokalen Reiseunternehmen mitfahren.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Beste Reisezeit f\u00fcr den Khao Sam Roi Yot National Park<\/h2>\n\n\n\n<p>Wettertechnisch gesehen ist die beste Zeit f\u00fcr einen Besuch von Khao Sam Roi Yot von Februar bis Mai, wenn die thermischen Winde kommen und Regen selten ist. Die meisten Tage bringen klaren Himmel, warmes Wetter und nicht zu viel Feuchtigkeit.<\/p>\n\n\n\n<p>Die Regenzeit dauert in diesem Teil des Golfs von Thailand von Juni bis Oktober. Wenn Sie also vorhaben, einige Outdoor-Abenteuer im Khao Sam Roi Yot National Park zu erleben, sollten Sie diese Monate meiden.<\/p>\n\n\n\n<p>Wenn Sie allerdings vorhaben, l\u00e4nger in der Gegend zu bleiben, werden Sie feststellen, dass die Regenzeit oft trockene Tage mit sich bringt - und wenn es regnet, dann oft nur f\u00fcr kurze Zeit. Wir sind im September von Pak Nam Pran nach Sam Roi Yot geradelt (was angeblich einer der feuchtesten Monate ist) und wir hatten den ganzen Tag strahlenden Sonnenschein!<\/p>\n\n\n\n<p>Zusammenfassend l\u00e4sst sich sagen: Die Regenzeit ist unberechenbar, macht aber das Erkunden der Natur nicht unm\u00f6glich.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Wie Sie den Khao Sam Roi Yot National Park in Ihre Thailand-Reiseplanung einbauen k\u00f6nnen<\/h3>\n\n\n\n<p>Ganz gleich, ob Sie auf der Suche nach einer Pause von der Gro\u00dfstadt sind oder auf der Suche nach ausgefallenen Alternativen f\u00fcr Ihr Thailand-Abenteuer als Rucksacktourist, ein Besuch des Khao Sam Roi Yot Nationalparks ist auf jeden Fall etwas, das Sie in Betracht ziehen sollten.<\/p>\n\n\n\n<p>Aber denken Sie nicht, Sie m\u00fcssten einen Besuch in diesem Teil des Landes planen und nur den Park besuchen:<\/p>\n\n\n\n<p>Maximieren Sie Ihre Zeit und Erfahrung, indem Sie Ihre Reise nach Sam Roi Yot mit einer abenteuerlichen, adrenalingeladenen Reise nach:<br><a href=\"https:\/\/extremenomads.life\/de\/outdoor-activities-bangkok\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bangkok <\/a>(3 Stunden entfernt)<br><a href=\"https:\/\/www.kqzyfj.com\/click-8884358-11552042?sid=khao-sam-roi-yot-national-park&amp;url=https%3A%2F%2Fwww.tripadvisor.com%2FAttractionProductReview-g297922-d11458194-Day_Trip_to_Sam_Roi_Yot_National_Park_from_Hua_Hin-Hua_Hin_Prachuap_Khiri_Khan_Pro.html\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Hua Hin<\/a> (40 Minuten entfernt)<br><a href=\"https:\/\/extremenomads.life\/de\/pranburi-thailand-travel-guide\/\" rel=\"noopener\">Pranburi<\/a> (25 Minuten entfernt).<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-ta-image wp-block-image\"><figure class=\"aligncenter is-resized\"><ta><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/extremenomads.life\/wp-content\/uploads\/2018\/09\/Sam-Roi-Yot-palms-2.jpg\" alt=\"Der Khao Sam Roi Yot Nationalpark ist eines der sch\u00f6nsten und am wenigsten touristischen Ziele in Thailand. Lesen Sie \u00fcber die besten Outdoor-Abenteuer in Sam Roi Yot, vom Wandern zur Phraya Nakhon H\u00f6hle bis hin zum Radfahren von Pranburi Thailand zum Park. Plus, wo man die besten Str\u00e4nde von Sam Roi Yot findet! Klicken Sie auf den Link, um mehr zu lesen. #hailand #Reisen #Nationalpark\" class=\"wp-image-7279\" width=\"368\" height=\"551\"><\/ta><figcaption><\/figcaption><\/figure><\/div>\n\n\n\n<p><em>Haben Sie eine brennende Frage \u00fcber Khao Sam Roi Yot National Park? Nutzen Sie den Kommentarbereich unten. M\u00f6chten Sie der Extreme Nomads-Community beitreten? Schauen Sie sich unsere exklusive&nbsp;<a rel=\"noopener noreferrer\" href=\"https:\/\/www.facebook.com\/groups\/extremenomads.life\/\" target=\"_blank\">Facebook-Gruppe!<\/a><\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Exploring Khao Sam Roi Yot National Park: Our Adventure in the Wild Khao Sam Roi Yot National Park (sometimes called Sam Roi Yod, which we can literally translate to Mountain of 300 Peaks) is a drop-dead slice of paradise on the western side of the Gulf of Thailand. Filled with [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":6094,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","footnotes":""},"categories":[441,468],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/extremenomads.life\/de\/wp-json\/wp\/v2\/posts\/6090"}],"collection":[{"href":"https:\/\/extremenomads.life\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/extremenomads.life\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/extremenomads.life\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/extremenomads.life\/de\/wp-json\/wp\/v2\/comments?post=6090"}],"version-history":[{"count":45,"href":"https:\/\/extremenomads.life\/de\/wp-json\/wp\/v2\/posts\/6090\/revisions"}],"predecessor-version":[{"id":45991,"href":"https:\/\/extremenomads.life\/de\/wp-json\/wp\/v2\/posts\/6090\/revisions\/45991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/extremenomads.life\/de\/wp-json\/wp\/v2\/media\/6094"}],"wp:attachment":[{"href":"https:\/\/extremenomads.life\/de\/wp-json\/wp\/v2\/media?parent=6090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/extremenomads.life\/de\/wp-json\/wp\/v2\/categories?post=6090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/extremenomads.life\/de\/wp-json\/wp\/v2\/tags?post=6090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}